{"id":902,"date":"2025-06-11T11:28:22","date_gmt":"2025-06-11T14:28:22","guid":{"rendered":"https:\/\/stattus4.com\/?p=902"},"modified":"2025-06-26T10:26:03","modified_gmt":"2025-06-26T13:26:03","slug":"stattus4-no-forum-ambicao-2030","status":"publish","type":"post","link":"https:\/\/stattus4.com\/es\/stattus4-no-forum-ambicao-2030\/","title":{"rendered":"Stattus4 en el 3er Foro Ambici\u00f3n 2030"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El 4 de junio de 2025, Stattus4 estuvo presente en <a href=\"https:\/\/forumambicao2030.com\/\">3er Foro Ambici\u00f3n 2030<\/a>, promovido por la Red Brasil del Pacto Mundial de las Naciones Unidas, en S\u00e3o Paulo. Como empresa de tecnolog\u00eda limpia, participamos en uno de los principales eventos sobre sostenibilidad, clima y acci\u00f3n corporativa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-1024x576.png\" alt=\"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030, acompanhando debates sobre a COP30 e inova\u00e7\u00e3o clim\u00e1tica com representantes do setor p\u00fablico e privado\" class=\"wp-image-907\" srcset=\"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-1024x576.png 1024w, https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-300x169.png 300w, https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-768x432.png 768w, https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-1536x864.png 1536w, https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog-18x10.png 18w, https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Reproducci\u00f3n \/ Foro Ambici\u00f3n 2030 \u2013 Pacto Mundial de las Naciones Unidas \u2013 Rede Brasil. Fuente: <a class=\"\" href=\"https:\/\/www.pactoglobal.org.br\/noticia\/manha-no-forum-ambicao-2030-reforca-protagonismo-do-brasil-no-clima-e-destaca-integridade-transicao-justa-e-combate-ao-greenwashing\/\">pactglobal.org.br<\/a> (publicado el 4 de junio de 2025).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n reuni\u00f3 a importantes l\u00edderes empresariales y pol\u00edticos, as\u00ed como a la sociedad civil, con el objetivo de generar compromisos concretos para acelerar el logro de los Objetivos de Desarrollo Sostenible (ODS). Y, sobre todo, para fortalecer la posici\u00f3n de Brasil como sede de la pr\u00f3xima COP30, que tendr\u00e1 lugar en Bel\u00e9m do Par\u00e1 en noviembre de 2025.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un espacio para voces diversas y compromisos reales<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mediado por la periodista Let\u00edcia Vidica, el foro trajo discusiones sobre temas fundamentales como inversi\u00f3n verde, cambio clim\u00e1tico, transici\u00f3n justa, combate al greenwashing, gobernanza clim\u00e1tica, ESG e innovaci\u00f3n sostenible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nombres que marcaron su presencia<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rachel Maia, Presidenta del Consejo del Pacto Mundial de las Naciones Unidas \u2013 Rede Brasil<\/li>\n\n\n\n<li>Silvia Rucks, Coordinadora Residente de la ONU en Brasil<\/li>\n\n\n\n<li>Dan Ioschpe, Campe\u00f3n de Alto Nivel sobre Clima de la COP30<\/li>\n\n\n\n<li>Giovanna Ewbank y Bruno Gagliasso, figuras p\u00fablicas, se posicionan a favor de la sostenibilidad.<\/li>\n\n\n\n<li>\u00c9dison Carlos y Ana Paula Carracedo, representantes de <a href=\"https:\/\/www.aegea.com.br\/\">EGEA<\/a>, empresa que utiliza nuestra tecnolog\u00eda para reducir p\u00e9rdidas de agua \u2013 cliente de Stattus4 en las ciudades de Mat\u00e3o (SP) y Rio de Janeiro (RJ).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las conversaciones reforzaron el papel de las empresas en la lucha contra la crisis clim\u00e1tica, la necesidad de transparencia en las pr\u00e1cticas de sostenibilidad y la urgencia de involucrar al sector privado en la acci\u00f3n clim\u00e1tica con responsabilidad e innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este compromiso cobra a\u00fan m\u00e1s importancia dado lo que est\u00e1 por venir:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">COP30: una oportunidad hist\u00f3rica para Brasil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/cop30.br\/pt-br\">Conferencia de las Partes de las Naciones Unidas sobre el Cambio Clim\u00e1tico<\/a> La COP es el mayor evento internacional de negociaci\u00f3n clim\u00e1tica. En su 30.\u00aa edici\u00f3n, celebrada por primera vez en Brasil, tendr\u00e1 su primera edici\u00f3n en suelo brasile\u00f1o en Bel\u00e9m, la puerta de entrada a la Amazonia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bel\u00e9m do Par\u00e1 en el centro del debate clim\u00e1tico global<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Bel\u00e9m acoger\u00e1 debates sobre emisiones, bosques tropicales, financiaci\u00f3n clim\u00e1tica y justicia ambiental. La elecci\u00f3n de Brasil como sede de la COP30 refuerza su liderazgo en soluciones sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las empresas brasile\u00f1as, este es un momento estrat\u00e9gico para mostrar c\u00f3mo la innovaci\u00f3n puede contribuir a objetivos clim\u00e1ticos ambiciosos y fortalecer alianzas y compromisos con el futuro del planeta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El papel de Stattus4 en la agenda ambiental<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2023, Stattus4 es signatario del <a href=\"https:\/\/stattus4.com\/es\/https-stattus4-fazemos-parte-do-pacto-global-da-onu\/\">Pacto Mundial<\/a> y participa en acciones a favor de objetivos globales. Alineado con <a href=\"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/\">Agenda 2030<\/a>Reconocemos que el desarrollo sostenible requiere acciones conjuntas e inmediatas para abordar desaf\u00edos como el cambio clim\u00e1tico, la escasez de recursos y la desigualdad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tecnolog\u00eda para preservar lo esencial<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con soluciones basadas en Inteligencia Artificial e IoT, Stattus4 ofrece soluciones que ampl\u00edan la resiliencia h\u00eddrica de los ecosistemas. Cuenta con tecnolog\u00eda innovadora para controlar y reducir las p\u00e9rdidas de agua en las redes de distribuci\u00f3n, contribuyendo as\u00ed a la eficiencia h\u00eddrica, la reducci\u00f3n de emisiones y la menor presi\u00f3n sobre las fuentes de agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al evitar el desperdicio de agua, la tecnolog\u00eda desarrollada por la empresa no s\u00f3lo ahorra recursos, sino que apoya la construcci\u00f3n de ciudades m\u00e1s resilientes al cambio clim\u00e1tico, alineando la innovaci\u00f3n y el impacto ambiental positivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Participaci\u00f3n de Stattus4 en el Foro Ambici\u00f3n 2030<\/strong> Refuerza nuestro compromiso con la innovaci\u00f3n clim\u00e1tica. Seguimos uniendo fuerzas con quienes creen que el futuro se construye hoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>El 4 de junio de 2025, Stattus4 estuvo presente en el 3.er Foro Ambici\u00f3n 2030, promovido por la Red Brasil del Pacto Mundial de las Naciones Unidas, en S\u00e3o Paulo. Como empresa de tecnolog\u00eda limpia, participamos en uno de los principales eventos sobre sostenibilidad, cambio clim\u00e1tico\u2026","protected":false},"author":2,"featured_media":907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030<\/title>\n<meta name=\"description\" content=\"Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030 e refor\u00e7a seu compromisso com a Agenda 2030 e a redu\u00e7\u00e3o de perdas de \u00e1gua rumo \u00e0 COP30.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stattus4.com\/es\/stattus4-no-forum-ambicao-2030\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030\" \/>\n<meta property=\"og:description\" content=\"Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030 e refor\u00e7a seu compromisso com a Agenda 2030 e a redu\u00e7\u00e3o de perdas de \u00e1gua rumo \u00e0 COP30.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stattus4.com\/es\/stattus4-no-forum-ambicao-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"Stattus4\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-11T14:28:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T13:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Stattus4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stattus4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/\"},\"author\":{\"name\":\"Stattus4\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"headline\":\"Stattus4 no 3\u00ba F\u00f3rum Ambi\u00e7\u00e3o 2030\",\"datePublished\":\"2025-06-11T14:28:22+00:00\",\"dateModified\":\"2025-06-26T13:26:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/\"},\"wordCount\":671,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capa-blog.png\",\"articleSection\":[\"Institucional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/\",\"url\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/\",\"name\":\"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capa-blog.png\",\"datePublished\":\"2025-06-11T14:28:22+00:00\",\"dateModified\":\"2025-06-26T13:26:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"description\":\"Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030 e refor\u00e7a seu compromisso com a Agenda 2030 e a redu\u00e7\u00e3o de perdas de \u00e1gua rumo \u00e0 COP30.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capa-blog.png\",\"contentUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/capa-blog.png\",\"width\":1600,\"height\":900,\"caption\":\"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030, Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030, acompanhando discuss\u00f5es sobre mudan\u00e7as clim\u00e1ticas, COP30 e sustentabilidade corporativa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/stattus4-no-forum-ambicao-2030\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/stattus4.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stattus4 no 3\u00ba F\u00f3rum Ambi\u00e7\u00e3o 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\",\"url\":\"https:\\\/\\\/stattus4.com\\\/\",\"name\":\"Stattus4\",\"description\":\"Desenvolvemos solu\u00e7\u00f5es que visam a economia de \u00e1gua atrav\u00e9s da detec\u00e7\u00e3o precoce de vazamentos e inconsist\u00eancias do consumo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stattus4.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\",\"name\":\"Stattus4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"caption\":\"Stattus4\"},\"url\":\"https:\\\/\\\/stattus4.com\\\/es\\\/author\\\/stattus4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stattus4 en el Foro Ambici\u00f3n 2030","description":"Stattus4 participa en el Foro Ambici\u00f3n 2030 y refuerza su compromiso con la Agenda 2030 y la reducci\u00f3n de las p\u00e9rdidas de agua de cara a la COP30.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stattus4.com\/es\/stattus4-no-forum-ambicao-2030\/","og_locale":"es_ES","og_type":"article","og_title":"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030","og_description":"Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030 e refor\u00e7a seu compromisso com a Agenda 2030 e a redu\u00e7\u00e3o de perdas de \u00e1gua rumo \u00e0 COP30.","og_url":"https:\/\/stattus4.com\/es\/stattus4-no-forum-ambicao-2030\/","og_site_name":"Stattus4","article_published_time":"2025-06-11T14:28:22+00:00","article_modified_time":"2025-06-26T13:26:03+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png","type":"image\/png"}],"author":"Stattus4","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Stattus4","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#article","isPartOf":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/"},"author":{"name":"Stattus4","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"headline":"Stattus4 no 3\u00ba F\u00f3rum Ambi\u00e7\u00e3o 2030","datePublished":"2025-06-11T14:28:22+00:00","dateModified":"2025-06-26T13:26:03+00:00","mainEntityOfPage":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/"},"wordCount":671,"commentCount":0,"image":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png","articleSection":["Institucional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/","url":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/","name":"Stattus4 en el Foro Ambici\u00f3n 2030","isPartOf":{"@id":"https:\/\/stattus4.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#primaryimage"},"image":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png","datePublished":"2025-06-11T14:28:22+00:00","dateModified":"2025-06-26T13:26:03+00:00","author":{"@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"description":"Stattus4 participa en el Foro Ambici\u00f3n 2030 y refuerza su compromiso con la Agenda 2030 y la reducci\u00f3n de las p\u00e9rdidas de agua de cara a la COP30.","breadcrumb":{"@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#primaryimage","url":"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png","contentUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2025\/06\/capa-blog.png","width":1600,"height":900,"caption":"Stattus4 no F\u00f3rum Ambi\u00e7\u00e3o 2030, Stattus4 participa do F\u00f3rum Ambi\u00e7\u00e3o 2030, acompanhando discuss\u00f5es sobre mudan\u00e7as clim\u00e1ticas, COP30 e sustentabilidade corporativa"},{"@type":"BreadcrumbList","@id":"https:\/\/stattus4.com\/stattus4-no-forum-ambicao-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/stattus4.com\/"},{"@type":"ListItem","position":2,"name":"Stattus4 no 3\u00ba F\u00f3rum Ambi\u00e7\u00e3o 2030"}]},{"@type":"WebSite","@id":"https:\/\/stattus4.com\/#website","url":"https:\/\/stattus4.com\/","name":"Estado4","description":"Desarrollamos soluciones que tienen como objetivo el ahorro de agua mediante la detecci\u00f3n temprana de fugas e inconsistencias en el consumo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stattus4.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8","name":"Estado4","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","caption":"Stattus4"},"url":"https:\/\/stattus4.com\/es\/author\/stattus4\/"}]}},"_links":{"self":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":13,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"predecessor-version":[{"id":926,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/902\/revisions\/926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media\/907"}],"wp:attachment":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/categories?post=902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/tags?post=902"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}