{"id":640,"date":"2024-11-25T11:35:26","date_gmt":"2024-11-25T14:35:26","guid":{"rendered":"https:\/\/stattus4.com\/?p=640"},"modified":"2024-11-25T12:04:22","modified_gmt":"2024-11-25T15:04:22","slug":"agenda-2030-o-chamado-para-transformar-o-mundo-agora","status":"publish","type":"post","link":"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/","title":{"rendered":"Agenda 2030: El llamado a transformar el mundo ahora"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Es cierto que el mundo ha avanzado en muchos aspectos. Mientras un solo \u00e1rbol sea deforestado de manera irregular, mientras una persona no tenga acceso a agua potable, no podemos parar. No debemos detenernos.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El cambio es urgente<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Millones de personas en todo el mundo todav\u00eda caminan m\u00e1s de 5 kil\u00f3metros al d\u00eda para ir a buscar agua, y esta agua a menudo no tiene la calidad suficiente para el consumo. Esta dura realidad nos conecta con varios Objetivos de Desarrollo Sostenible (ODS):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#44a4dc\" class=\"has-inline-color\">ODS 6<\/mark> <\/strong>\u2013 Agua potable y saneamiento, porque el agua potable sigue siendo un privilegio de pocos.<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0);color:#d31b1b\" class=\"has-inline-color\"><strong>ODS 1<\/strong> <\/mark>\u2013 Erradicaci\u00f3n de la pobreza, ya que el acceso b\u00e1sico al agua est\u00e1 directamente relacionado con la desigualdad social.<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0);color:#e79e01\" class=\"has-inline-color\"><strong>ODS 7<\/strong> <\/mark>\u2013 Energ\u00eda asequible y limpia, que puede hacer m\u00e1s eficiente el transporte y tratamiento del agua.<\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0);color:#e966bb\" class=\"has-inline-color\"><strong>ODS 10<\/strong><\/mark> \u2013 Reducci\u00f3n de las desigualdades, ya que quienes m\u00e1s sufren esta carencia son las poblaciones marginadas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Una cuesti\u00f3n de g\u00e9nero: 90% son mujeres<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un dato alarmante es que el 90% de las personas que buscan diariamente esta agua son mujeres. Esta estad\u00edstica destaca la desigualdad de g\u00e9nero, destacada en el ODS 5: Igualdad de g\u00e9nero.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Las 3 I de la Agenda 2030<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Agenda 2030 est\u00e1 interconectada, indivisible e integrada. Esto significa que no podemos resolver un problema de forma aislada. Necesitamos ver el conjunto: la pobreza, el medio ambiente, la salud, la educaci\u00f3n, la igualdad y el desarrollo sostenible est\u00e1n conectados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQui\u00e9n es responsable?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De todos nosotros. La Agenda 2030 es un compromiso global que requiere una acci\u00f3n conjunta de&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gobiernos, para crear pol\u00edticas p\u00fablicas que prioricen los ODS.<\/li>\n\n\n\n<li>\u00a0Empresas, que tienen el poder de transformar recursos y pr\u00e1cticas en impacto positivo.<\/li>\n\n\n\n<li>La sociedad civil, como impulsora del cambio, exigiendo y participando de soluciones.<\/li>\n\n\n\n<li>Individuos, porque cada peque\u00f1a actitud puede generar un efecto en cadena.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Independientemente del sector en el que operen, las empresas tienen un enorme potencial de transformaci\u00f3n. Adoptar pr\u00e1cticas sostenibles, alinear estrategias con los ODS e invertir en innovaci\u00f3n social son acciones fundamentales para alcanzar objetivos globales. La responsabilidad es grande y el impacto ser\u00e1 a\u00fan mayor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ahora es lo que importa<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Agenda 2030 no trata de un futuro lejano. Se trata de lo que estamos haciendo hoy para construir un mundo m\u00e1s justo, equilibrado y sostenible. \u00bfVamos juntos?<\/p>","protected":false},"excerpt":{"rendered":"<p>Es cierto que el mundo ha avanzado en muchos aspectos. Mientras un solo \u00e1rbol sea deforestado de manera irregular, mientras una persona no tenga acceso a agua potable, no podemos parar. No debemos detenernos.  El cambio es urgente...","protected":false},"author":2,"featured_media":642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda 2030: O Chamado para Transformar o Mundo Agora - Stattus4<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda 2030: O Chamado para Transformar o Mundo Agora - Stattus4\" \/>\n<meta property=\"og:description\" content=\"\u00c9 verdade que o mundo tem avan\u00e7ado em muitos aspectos.&nbsp; Enquanto uma \u00fanica \u00e1rvore for desmatada irregularmente, enquanto uma pessoa n\u00e3o tiver acesso \u00e0 \u00e1gua pot\u00e1vel, n\u00e3o podemos parar. N\u00e3o devemos parar.&nbsp;&nbsp; A mudan\u00e7a \u00e9 urgente Milh\u00f5es de pessoas ao redor do mundo ainda caminham mais de 5km por dia para buscar \u00e1gua, e muitas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/\" \/>\n<meta property=\"og:site_name\" content=\"Stattus4\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-25T14:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T15:04:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Stattus4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stattus4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/\"},\"author\":{\"name\":\"Stattus4\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"headline\":\"Agenda 2030: O Chamado para Transformar o Mundo Agora\",\"datePublished\":\"2024-11-25T14:35:26+00:00\",\"dateModified\":\"2024-11-25T15:04:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/\"},\"wordCount\":401,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Imagem-blog.png\",\"articleSection\":[\"Institucional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/\",\"url\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/\",\"name\":\"Agenda 2030: O Chamado para Transformar o Mundo Agora - Stattus4\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Imagem-blog.png\",\"datePublished\":\"2024-11-25T14:35:26+00:00\",\"dateModified\":\"2024-11-25T15:04:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Imagem-blog.png\",\"contentUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Imagem-blog.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/stattus4.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda 2030: O Chamado para Transformar o Mundo Agora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\",\"url\":\"https:\\\/\\\/stattus4.com\\\/\",\"name\":\"Stattus4\",\"description\":\"Desenvolvemos solu\u00e7\u00f5es que visam a economia de \u00e1gua atrav\u00e9s da detec\u00e7\u00e3o precoce de vazamentos e inconsist\u00eancias do consumo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stattus4.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\",\"name\":\"Stattus4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"caption\":\"Stattus4\"},\"url\":\"https:\\\/\\\/stattus4.com\\\/es\\\/author\\\/stattus4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda 2030: El llamado a transformar el mundo ahora - Stattus4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/","og_locale":"es_ES","og_type":"article","og_title":"Agenda 2030: O Chamado para Transformar o Mundo Agora - Stattus4","og_description":"\u00c9 verdade que o mundo tem avan\u00e7ado em muitos aspectos.&nbsp; Enquanto uma \u00fanica \u00e1rvore for desmatada irregularmente, enquanto uma pessoa n\u00e3o tiver acesso \u00e0 \u00e1gua pot\u00e1vel, n\u00e3o podemos parar. N\u00e3o devemos parar.&nbsp;&nbsp; A mudan\u00e7a \u00e9 urgente Milh\u00f5es de pessoas ao redor do mundo ainda caminham mais de 5km por dia para buscar \u00e1gua, e muitas [&hellip;]","og_url":"https:\/\/stattus4.com\/es\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/","og_site_name":"Stattus4","article_published_time":"2024-11-25T14:35:26+00:00","article_modified_time":"2024-11-25T15:04:22+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png","type":"image\/png"}],"author":"Stattus4","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Stattus4","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#article","isPartOf":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/"},"author":{"name":"Stattus4","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"headline":"Agenda 2030: O Chamado para Transformar o Mundo Agora","datePublished":"2024-11-25T14:35:26+00:00","dateModified":"2024-11-25T15:04:22+00:00","mainEntityOfPage":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/"},"wordCount":401,"commentCount":0,"image":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png","articleSection":["Institucional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/","url":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/","name":"Agenda 2030: El llamado a transformar el mundo ahora - Stattus4","isPartOf":{"@id":"https:\/\/stattus4.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#primaryimage"},"image":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png","datePublished":"2024-11-25T14:35:26+00:00","dateModified":"2024-11-25T15:04:22+00:00","author":{"@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"breadcrumb":{"@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#primaryimage","url":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png","contentUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/11\/Imagem-blog.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/stattus4.com\/agenda-2030-o-chamado-para-transformar-o-mundo-agora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/stattus4.com\/"},{"@type":"ListItem","position":2,"name":"Agenda 2030: O Chamado para Transformar o Mundo Agora"}]},{"@type":"WebSite","@id":"https:\/\/stattus4.com\/#website","url":"https:\/\/stattus4.com\/","name":"Estado4","description":"Desarrollamos soluciones que tienen como objetivo el ahorro de agua mediante la detecci\u00f3n temprana de fugas e inconsistencias en el consumo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stattus4.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8","name":"Estado4","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","caption":"Stattus4"},"url":"https:\/\/stattus4.com\/es\/author\/stattus4\/"}]}},"_links":{"self":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":2,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/640\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/640\/revisions\/643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media\/642"}],"wp:attachment":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media?parent=640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/categories?post=640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/tags?post=640"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}