{"id":616,"date":"2024-10-31T16:32:17","date_gmt":"2024-10-31T19:32:17","guid":{"rendered":"https:\/\/stattus4.com\/?p=616"},"modified":"2024-10-31T16:50:31","modified_gmt":"2024-10-31T19:50:31","slug":"coquetel-conectando-solucoes-transformando-o-saneamento","status":"publish","type":"post","link":"https:\/\/stattus4.com\/es\/coquetel-conectando-solucoes-transformando-o-saneamento\/","title":{"rendered":"C\u00f3ctel \u201cConectando Soluciones, Transformando el Saneamiento\u201d"},"content":{"rendered":"<p class=\"wp-block-paragraph\">S\u00e3o Paulo, 21 de octubre de 2024 \u2013 El auditorio ABES fue el escenario del c\u00f3ctel \u201cConectando Solu\u00e7\u00f5es, Transformando o Saneamento\u201d, promovido por Stattus4 en colaboraci\u00f3n con Bottom Up y Padtec.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue un verdadero \u00e9xito, reuniendo a decenas de profesionales del sector sanitario, creando un ambiente propicio para el networking y el intercambio de experiencias.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participantes de diferentes concesionarias, como SANASA, Rio + Saneamento, SABESP y Aegea, se reunieron para compartir ideas para la gesti\u00f3n de p\u00e9rdidas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-1024x576.png\" alt=\"\" class=\"wp-image-618\" srcset=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-1024x576.png 1024w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-300x169.png 300w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-768x432.png 768w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-18x10.png 18w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/3Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al c\u00f3ctel tambi\u00e9n asistieron el superintendente Alexandre Ander\u00e1os y el director Filipe Sampaio, de la Agencia Nacional del Agua (ANA), quienes aportaron valiosos conocimientos sobre las tendencias actuales del sector.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-1024x576.png\" alt=\"\" class=\"wp-image-619\" srcset=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-1024x576.png 1024w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-300x169.png 300w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-768x432.png 768w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1-18x10.png 18w, https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/4Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas gracias a todos los invitados que nos acompa\u00f1aron en esta velada memorable. Para aquellos que no pudieron asistir, sepan que en 2025 tendremos la segunda edici\u00f3n de este evento.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Las entradas para el c\u00f3ctel son restringidas y seleccionadas, as\u00ed que mantente atento a los anuncios de Stattus4 para asegurar tu participaci\u00f3n en futuras ediciones.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00a1Transformemos el saneamiento juntos!? <\/em><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/drive.google.com\/drive\/folders\/12KU9e_DZUOwWBz1zG5bIf5-K9p4yyfHa?usp=sharing\">\ud83d\udd17 Mira las fotos oficiales del evento \ud83d\udd17<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Paulo, 21 de octubre de 2024 \u2013 El auditorio ABES fue el escenario del c\u00f3ctel \u201cConectando Solu\u00e7\u00f5es, Transformando o Saneamento\u201d, promovido por Stattus4 en colaboraci\u00f3n con Bottom Up y Padtec. El evento fue un verdadero \u00e9xito,\u2026","protected":false},"author":2,"featured_media":624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coquetel &quot;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&quot; - Stattus4<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stattus4.com\/es\/coquetel-conectando-solucoes-transformando-o-saneamento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coquetel &quot;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&quot; - Stattus4\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o Paulo, 21 de outubro de 2024 \u2013 O audit\u00f3rio da ABES foi palco do coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;, promovido pela Stattus4 em parceria com a Bottom Up e a Padtec.&nbsp; O evento foi um verdadeiro sucesso, reunindo dezenas de profissionais do setor de saneamento, criando um ambiente prop\u00edcio para networking e troca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stattus4.com\/es\/coquetel-conectando-solucoes-transformando-o-saneamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Stattus4\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T19:32:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T19:50:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Stattus4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stattus4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/\"},\"author\":{\"name\":\"Stattus4\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"headline\":\"Coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;\",\"datePublished\":\"2024-10-31T19:32:17+00:00\",\"dateModified\":\"2024-10-31T19:50:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/\"},\"wordCount\":200,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png\",\"articleSection\":[\"Institucional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/\",\"url\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/\",\"name\":\"Coquetel \\\"Conectando Solu\u00e7\u00f5es, Transformando o Saneamento\\\" - Stattus4\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png\",\"datePublished\":\"2024-10-31T19:32:17+00:00\",\"dateModified\":\"2024-10-31T19:50:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png\",\"contentUrl\":\"https:\\\/\\\/stattus4.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/coquetel-conectando-solucoes-transformando-o-saneamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/stattus4.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#website\",\"url\":\"https:\\\/\\\/stattus4.com\\\/\",\"name\":\"Stattus4\",\"description\":\"Desenvolvemos solu\u00e7\u00f5es que visam a economia de \u00e1gua atrav\u00e9s da detec\u00e7\u00e3o precoce de vazamentos e inconsist\u00eancias do consumo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stattus4.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stattus4.com\\\/#\\\/schema\\\/person\\\/24e0184e92a7ad6524942dbbd79a69d8\",\"name\":\"Stattus4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g\",\"caption\":\"Stattus4\"},\"url\":\"https:\\\/\\\/stattus4.com\\\/es\\\/author\\\/stattus4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3ctel &quot;Conectando Soluciones, Transformando el Saneamiento&quot; - Stattus4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stattus4.com\/es\/coquetel-conectando-solucoes-transformando-o-saneamento\/","og_locale":"es_ES","og_type":"article","og_title":"Coquetel \"Conectando Solu\u00e7\u00f5es, Transformando o Saneamento\" - Stattus4","og_description":"S\u00e3o Paulo, 21 de outubro de 2024 \u2013 O audit\u00f3rio da ABES foi palco do coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;, promovido pela Stattus4 em parceria com a Bottom Up e a Padtec.&nbsp; O evento foi um verdadeiro sucesso, reunindo dezenas de profissionais do setor de saneamento, criando um ambiente prop\u00edcio para networking e troca [&hellip;]","og_url":"https:\/\/stattus4.com\/es\/coquetel-conectando-solucoes-transformando-o-saneamento\/","og_site_name":"Stattus4","article_published_time":"2024-10-31T19:32:17+00:00","article_modified_time":"2024-10-31T19:50:31+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png","type":"image\/png"}],"author":"Stattus4","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Stattus4","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#article","isPartOf":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/"},"author":{"name":"Stattus4","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"headline":"Coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;","datePublished":"2024-10-31T19:32:17+00:00","dateModified":"2024-10-31T19:50:31+00:00","mainEntityOfPage":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/"},"wordCount":200,"commentCount":0,"image":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png","articleSection":["Institucional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/","url":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/","name":"C\u00f3ctel &quot;Conectando Soluciones, Transformando el Saneamiento&quot; - Stattus4","isPartOf":{"@id":"https:\/\/stattus4.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#primaryimage"},"image":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#primaryimage"},"thumbnailUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png","datePublished":"2024-10-31T19:32:17+00:00","dateModified":"2024-10-31T19:50:31+00:00","author":{"@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8"},"breadcrumb":{"@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#primaryimage","url":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png","contentUrl":"https:\/\/stattus4.com\/wp-content\/uploads\/2024\/10\/1Coquetel-Conectando-Solucoes-Transformando-Saneamento-Stattus4-1980x1080-2.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/stattus4.com\/coquetel-conectando-solucoes-transformando-o-saneamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/stattus4.com\/"},{"@type":"ListItem","position":2,"name":"Coquetel &#8220;Conectando Solu\u00e7\u00f5es, Transformando o Saneamento&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/stattus4.com\/#website","url":"https:\/\/stattus4.com\/","name":"Estado4","description":"Desarrollamos soluciones que tienen como objetivo el ahorro de agua mediante la detecci\u00f3n temprana de fugas e inconsistencias en el consumo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stattus4.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/stattus4.com\/#\/schema\/person\/24e0184e92a7ad6524942dbbd79a69d8","name":"Estado4","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de05dd3198a6638367b427f1973702cd6a6d904721557152fd76b121471cfb8a?s=96&d=mm&r=g","caption":"Stattus4"},"url":"https:\/\/stattus4.com\/es\/author\/stattus4\/"}]}},"_links":{"self":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/comments?post=616"}],"version-history":[{"count":4,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/616\/revisions"}],"predecessor-version":[{"id":626,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/posts\/616\/revisions\/626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media\/624"}],"wp:attachment":[{"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/media?parent=616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/categories?post=616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stattus4.com\/es\/wp-json\/wp\/v2\/tags?post=616"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}